{"id":81787,"date":"2019-06-22T11:38:53","date_gmt":"2019-06-22T09:38:53","guid":{"rendered":"https:\/\/jfrog.com\/?p=81787"},"modified":"2024-04-10T15:41:10","modified_gmt":"2024-04-10T13:41:10","slug":"artifactory-vs-github-packages-faq","status":"publish","type":"post","link":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/","title":{"rendered":"GitHub Packages vs. Artifactory"},"content":{"rendered":"<p><img decoding=\"async\" class=\"wp-image-46500 size-full alignnone\" src=\"https:\/\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130800\/863x300-2.png\" alt=\"JFrog vs Github\" width=\"863\" height=\"300\" srcset=\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130800\/863x300-2.png?speedsize=w_863 863w, https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130800\/863x300-2.png?speedsize=w_300 300w, https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130800\/863x300-2.png?speedsize=w_768 768w\" sizes=\"(max-width: 863px) 100vw, 863px\" \/><\/p>\n<p><b><i>Hinweis<\/i><\/b><i><span style=\"font-weight: 400\">: Dieser Beitrag wurde aktualisiert, um der aktuellen Situation ab dem 1. Juni 2021 Rechnung zu tragen.<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400\">Wir haben geh\u00f6rt, dass es in der Community einige Verwirrung \u00fcber den Dienst von GitHub gibt \u2013 <\/span><a href=\"https:\/\/github.com\/features\/package-registry\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">GitHub Package Registry<\/span><\/a><span style=\"font-weight: 400\">. Es ist ein Package Manager, der mit einer GitHub-Lizenz verf\u00fcgbar ist und es Entwicklern erm\u00f6glicht, Software Pakete neben ihrem Quellcode zu ver\u00f6ffentlichen. Wir wollten klarstellen, was dies f\u00fcr unsere treuen Artifactory-Kunden und -Benutzer bedeutet. <\/span><\/p>\n<p><span style=\"font-weight: 400\">GitHub ist ein langj\u00e4hriger Partner (und Kunde) von JFrog, und wir sehen, dass sich die Vision von Liquid Software auf deren Open Source-Kollaborationsplattform auswirkt. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Ihr Service ist ein Schritt in Richtung des Flusses von Open Source-Code aus der &#8220;Wildnis&#8221; von GitHub in Software Pakete, die von Unternehmen auf ihrem Weg zu einer zuverl\u00e4ssigen, sicheren und aktuellen Produktionsumgebung verwaltet werden k\u00f6nnen. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Software Pakete geh\u00f6ren zu den wichtigsten Bestandteilen des <a href=\"https:\/\/jfrog.com\/de\/devops-tools\/article\/was-ist-der-software-lebenszyklus\/\">Software-Lebenszyklus<\/a>, so dass die \u00dcbersetzung von OSS-Software in Pakete deren Verwaltung und Kontrolle wesentlich erleichtert. Dies ist f\u00fcr Unternehmen von ausschlaggebender Bedeutung. Mit GitHub Packages haben wir jetzt viel mehr Package Registry-Quellen (wir nennen sie &#8220;Remote-Repositories&#8221;), die eng mit den Quell-Repos verbunden sind und die importiert, verwaltet, gescannt, mit Unternehmenssoftware kombiniert und in eine Produktionsumgebung eingebunden werden k\u00f6nnen. Wir hoffen, dass dieses neue Leistungsmerkmal es Unternehmen erm\u00f6glicht, Open Source-Software zu nutzen wie nie zuvor. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Wir begr\u00fc\u00dfen Technologien, die Entwickler produktiver machen, und wir freuen uns, dass GitHub in den Bereich der Paketverwaltung einsteigt.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Was kann dieser Package Manager leisten?<\/span><\/h2>\n<p><span style=\"font-weight: 400\">GitHub Package Registry bietet Nutzern von GitHub neben ihren versionierten Repositories f\u00fcr Quellcode einen zus\u00e4tzlichen Package Manager. Es funktioniert sowohl als privates als auch als \u00f6ffentliches Repository und Entwickler k\u00f6nnen die gleichen Anmeldedaten wie f\u00fcr GitHub verwenden. Support f\u00fcr CI wird gr\u00f6\u00dftenteils durch den begrenzten Bestand von GitHub actions erreicht.<\/span><\/p>\n<p><b>Was ist der Unterschied zwischen GitHub Package Registry und JFrog Artifactory?<\/b><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Das ist eine ganz wichtige Frage \u2013 lassen Sie uns also einen kurzen Blick darauf werfen und dann einige h\u00e4ufig gestellte Fragen zu GitHub Packages im Vergleich zu JFrog Artifactory beantworten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Die Unterst\u00fctzung von sechs Pakettypen f\u00fcr Open Source durch GitHub ist ein gro\u00dfer Schritt in die richtige Richtung, der der Welt helfen wird, sich in Richtung <\/span><a href=\"https:\/\/liquidsoftware.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">fl\u00fcssige Software<\/span><\/a><span style=\"font-weight: 400\"> zu bewegen. Es kann helfen, die Kette des <\/span><b>Vertrauens<\/b><span style=\"font-weight: 400\"> von der Quelle \u00fcber Artifactory bis zur Produktion f\u00fcr Open Source-Komponenten zu st\u00e4rken.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aber lassen Sie uns klarstellen, was es nicht ist: Es ist kein Ersatz f\u00fcr Artifactory. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Es stellt nicht den nachvollziehbaren, vertrauensw\u00fcrdigen Pfad f\u00fcr alle Ihre Artefakte dar, der f\u00fcr eine effektive DevOps-Pipeline notwendig ist. Es ist nicht einmal ein Ersatz f\u00fcr zentralisierte Repositories wie DockerHub, Maven Central, PyPi Repo oder npm.<\/span><\/p>\n<h2><span style=\"font-weight: 400\">Einige h\u00e4ufig gestellte Fragen<\/span><\/h2>\n<h3><b>Ich verwende Artifactory. Ist GitHub Package Registry ein Konkurrenzprodukt? <\/b><\/h3>\n<p><span style=\"font-weight: 400\">Nein. GitHub Package Registry ist kein Konkurrenzprodukt zu Artifactory, da es viele Funktionen <\/span><b>nicht<\/b><span style=\"font-weight: 400\"> unterst\u00fctzt, die von modernen Bin\u00e4r-Repositories verlangt werden. W\u00e4hrend GitHub Ihre Open Source-Pakete verwalten kann, liegt es an Ihnen, den Rest Ihrer Artefakte \u00fcber Ihre Pipeline zu verwalten. <\/span><span style=\"font-weight: 400\">Artifactory bleibt Ihre zuverl\u00e4ssige Quelle f\u00fcr Bin\u00e4rdateien<\/span><span style=\"font-weight: 400\">, die Build-Informationen speichert, Builds durch Pr\u00fcfung zur Produktionsreife bringt, auf Sicherheit scannt und die f\u00fcr schnelle, sichere Software-Releases erforderliche Transparenz und Einsicht in Ihre Builds bietet.<\/span><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<h3><b>Bietet GitHub Unternehmen eine lokale L\u00f6sung oder eine Hybrid-L\u00f6sung? <\/b><\/h3>\n<p><span style=\"font-weight: 400\">GitHub bietet \u00fcber GitHub Enterprise Server, dem umfangreichsten Angebot, eine lokale Option an. Es kann mit einem Enterprise Cloud-Konto kombiniert werden, um ein hybrides System \u00fcber GitHub Connect zu erstellen. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Artifactory bietet eine breite Palette von Optionen an, wobei jede Lizenzstufe sowohl in der Cloud als auch lokal verf\u00fcgbar ist. JFrog erm\u00f6glicht es Ihnen auch, Ihre Hosting-Cloud-Plattform von jedem der gro\u00dfen Cloud-Anbieter (<\/span><span style=\"font-weight: 400\"><a href=\"https:\/\/jfrog.com\/de\/artifactory\/cloud-native-aws\/\">AWS<\/a>, <a href=\"https:\/\/jfrog.com\/de\/artifactory\/cloud-native-gcp\/\">GCP<\/a> und <a href=\"https:\/\/jfrog.com\/de\/artifactory\/cloud-native-azure\/\">Azure<\/a>)<\/span><span style=\"font-weight: 400\"> zu w\u00e4hlen oder mehr als eine f\u00fcr eine Multi-Cloud-Strategie zu unterhalten. GitHub hostet alle Cloud-Service-Levels (SaaS) auf einer einzigen, nicht spezifizierten Cloud-Plattform, was eine Multi-Cloud-Redundanz unm\u00f6glich macht. <\/span><\/p>\n<p><span style=\"font-weight: 400\">Artifactory verf\u00fcgt \u00fcber viele weitere Funktionen, die sowohl f\u00fcr lokale als auch f\u00fcr hybride Umgebungen wichtig sind. Weitere Details finden Sie unten.<\/span><span style=\"font-weight: 400\"><br \/>\n<\/span><\/p>\n<h3><b>Unterst\u00fctzt GitHub <\/b><b>alle<\/b><b> meine Pakete?<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Nur <\/span><b>sechs<\/b><span style=\"font-weight: 400\">: npm, Docker, Maven, Gradle, NuGet und RubyGems.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Artifactory ist vollst\u00e4ndig universell und<\/span><b> unterst\u00fctzt 30 Technologien, und es werden st\u00e4ndig mehr.<\/b><span style=\"font-weight: 400\">. Dazu geh\u00f6ren Repositories f\u00fcr In-Demand-Pakettypen wie pip\/twine (f\u00fcr Python), Go-Module, Conan (f\u00fcr C\/C++) und <a href=\"https:\/\/jfrog.com\/de\/integration\/cargo-registry\/\">Cargo<\/a> (f\u00fcr Rust). Au\u00dferdem kann Artifactory Docker-Registries hosten, die<\/span> <a href=\"https:\/\/jfrog.com\/de\/blog\/steer-oci-to-kubernetes-with-artifactory-and-helm-3\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">OCI-konform sind<\/span><\/a><span style=\"font-weight: 400\">, und unterst\u00fctzt <\/span><a href=\"https:\/\/jfrog.com\/de\/integration\/helm-repository\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Repositories f\u00fcr Helm 2 and 3<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<h3><b>L\u00e4sst sich GitHub mit anderen Tools von Drittanbietern integrieren?<\/b><\/h3>\n<p><span style=\"font-weight: 400\">W\u00e4hrend es zahlreiche Integrationen f\u00fcr GitHub gibt, sind Integrationen f\u00fcr GitHub-Pakete begrenzt. <\/span><a href=\"https:\/\/jfrog.com\/de\/integration\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Artifactory hat einen umfangreichen Katalog von Integrationen<\/span><\/a><span style=\"font-weight: 400\"> f\u00fcr die Verwendung mit den am weitesten verbreiteten CI\/CD-Servern, IDEs, Issue-Trackern und anderen DevOps-Tools und -Plattformen. Noch mehr Integrationen sind von unseren <\/span><a href=\"https:\/\/jfrog.com\/de\/partner\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">vielen Technologiepartnern<\/span><\/a><span style=\"font-weight: 400\"> verf\u00fcgbar.<\/span><\/p>\n<h3><b>Wie stellt GitHub die Verwaltung der Pakete von Drittanbietern bereit?<\/b><\/h3>\n<p><span style=\"font-weight: 400\">GitHub konzentriert sich auf <\/span><span style=\"font-weight: 400\">die in GitHub Packages vorhandenen<\/span><span style=\"font-weight: 400\"> Pakete und bietet keine klare L\u00f6sung f\u00fcr die Verwaltung der Pakete von Drittanbietern. Es gibt keine Option als Proxy anderer Repositories und es ist nicht klar, was Sie tun sollen, um Pakete von Drittanbietern in Ihrem Repository zu hosten.<\/span><\/p>\n<h3><b>Was kann Artifactory, was GitHub nicht kann?<\/b><\/h3>\n<p><span style=\"font-weight: 400\">Ziemlich viel. Hier sind die wichtigsten Merkmale, die Sie sich merken sollten:<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400\"><b>Universell<\/b><span style=\"font-weight: 400\"> &#8211; Unterst\u00fctzt 30 Pakete, viele Integrationsm\u00f6glichkeiten, REST-APIs und eine leistungsf\u00e4hige Abfragesprache (AQL).<\/span><\/li>\n<li style=\"font-weight: 400\"><b>R\u00fcckverfolgbarkeit<\/b><span style=\"font-weight: 400\"> \u2013 Stellt die <\/span><a href=\"https:\/\/github.com\/jfrog\/build-info\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">buildinfo <\/span><\/a><span style=\"font-weight: 400\">bereit, es Ihnen erm\u00f6glicht, die Freigabe besser zu automatisieren und zu beschleunigen.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Flexibilit\u00e4t<\/b><span style=\"font-weight: 400\"> \u2013 Kann lokal oder in der Cloud gehostet (Multi-Cloud), verwaltet, selbst verwaltet oder als Teil einer hybriden Umgebung implementiert werden.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Robust<\/b><span style=\"font-weight: 400\"> \u2013 Proxy-Modus f\u00fcr viele Quellen bietet Caching f\u00fcr Geschwindigkeit und Schutz vor Verbindungsausf\u00e4llen und Disaster Recovery.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Security\/<a href=\"https:\/\/jfrog.com\/de\/learn\/devsecops\/\">DevSecOps<\/a><\/b><span style=\"font-weight: 400\"> \u2013 <\/span><a href=\"https:\/\/jfrog.com\/de\/xray\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">JFrog Xray<\/span><\/a><span style=\"font-weight: 400\"> erm\u00f6glicht es Ihnen, die Geschwindigkeit Ihrer Entwickler aufrechtzuerhalten und hilft gleichzeitig, bekannte Schwachstellen aus der ver\u00f6ffentlichten Software herauszuhalten.<\/span><\/li>\n<li style=\"font-weight: 400\"><b>Enterprise-Ready <\/b><span style=\"font-weight: 400\">\u2013 Unterst\u00fctzung f\u00fcr Push\/Pull-Replikation und Hochverf\u00fcgbarkeit, mit einer Reihe von zus\u00e4tzlichen Produkten, aus denen sich die <\/span><a href=\"https:\/\/jfrog.com\/de\/enterprise-plus-platform\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">JFrog Plattform<\/span><\/a><span style=\"font-weight: 400\"> zusammensetzt und die DevOps im globalen Ma\u00dfstab erm\u00f6glichen.<\/span><\/li>\n<\/ol>\n<h2><span style=\"font-weight: 400\">Was sollten Sie als n\u00e4chstes tun?<\/span><\/h2>\n<p><span style=\"font-weight: 400\"><a href=\"https:\/\/jfrog.com\/de\/artifactory\/\">Artifactory<\/a> ist ein ausgereiftes, dem Branchenstandard entsprechendes <a href=\"https:\/\/jfrog.com\/de\/devops-tools\/article\/what-is-an-artifact-repository\/\">Artefakt-Repository<\/a><\/span><span style=\"font-weight: 400\">, das Ihnen die Wahl der Werkzeuge und Plattformen \u00fcberl\u00e4sst, die Sie in Ihrer Pipeline verwenden. Es versetzt Startups und globale Unternehmen gleicherma\u00dfen in die Lage, die Entwicklungsgeschwindigkeit zu erh\u00f6hen und gleichzeitig die Sicherheit in der ben\u00f6tigten Gr\u00f6\u00dfenordnung zu gew\u00e4hrleisten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Aus diesem Grund vertrauen Millionen von Nutzern und Tausende von Kunden auf Artifactory, darunter die Mehrheit der Fortune-100-Unternehmen. Die Top-Marken der Welt, wie LinkedIn, Facebook, Morgan Stanley, CapitalOne, Cisco, Netflix, Uber, VMware und Spotify verlassen sich auf JFrog, um ihre Bin\u00e4rdateien f\u00fcr ihre gesch\u00e4ftskritischen Anwendungen zu verwalten.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Wer nutzt noch Artifactory? GitHub macht es, und zwar f\u00fcr die interne Entwicklung.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Artifactory ist die Schl\u00fcssell\u00f6sung hinter JFrogs <a href=\"https:\/\/jfrog.com\/de\/software-supply-chain-platform\/\">Software-Supply-Chain-Plattform<\/a>, die Ihre digitale Transformation von Anfang bis Ende vorantreiben kann. Weitere Einzelheiten finden Sie in unserem umfangreichen <\/span><a href=\"https:\/\/jfrog.com\/de\/blog\/github-vs-jfrog-who-can-do-the-job-for-devops\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">Vergleich zwischen JFrog und GitHub<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n<h3><span style=\"font-weight: 400\">Sie haben noch keine Erfahrung mit Artifactory? <\/span><\/h3>\n<p><span style=\"font-weight: 400\">Nichts kann die praktische Erfahrung mit einem <\/span><a href=\"https:\/\/jfrog.com\/de\/start-free\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400\">kostenloses JFrog Cloud-Konto<\/span><\/a><span style=\"font-weight: 400\"> ersetzen. Geben Sie Artifactory und der JFrog Plattform eine vollst\u00e4ndige Bewertung \u2013 f\u00fcr die Bed\u00fcrfnisse von heute und die DevOps-Anforderungen von morgen. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hinweis: Dieser Beitrag wurde aktualisiert, um der aktuellen Situation ab dem 1. Juni 2021 Rechnung zu tragen. Wir haben geh\u00f6rt, dass es in der Community einige Verwirrung \u00fcber den Dienst von GitHub gibt \u2013 GitHub Package Registry. Es ist ein Package Manager, der mit einer GitHub-Lizenz verf\u00fcgbar ist und es Entwicklern erm\u00f6glicht, Software Pakete neben &hellip;<\/p>\n","protected":false},"author":140,"featured_media":46502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9205],"tags":[],"class_list":["post-81787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Artifactory- im Vergleich zur GitHub Package Registry FAQs | JFrog Artifactory<\/title>\n<meta name=\"description\" content=\"Wie schneidet der Package Manager von GitHub im Vergleich zu Artifactory ab? Ein kurzer \u00dcberblick der Leistungsf\u00e4higkeiten zeigt, was dies f\u00fcr Ihre Repositories und DevOps bedeutet.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts\/81787\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was GitHub und Artifactory alles bieten\" \/>\n<meta property=\"og:description\" content=\"Wie schl\u00e4gt sich der Package Manager von GitHub im Vergleich zu Artifactory? Ein kurzer \u00dcberblick zeigt, was das f\u00fcr Ihre Repositories und DevOps bedeutet &gt;&gt;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\" \/>\n<meta property=\"og:site_name\" content=\"JFrog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/artifrog\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-22T09:38:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-10T13:41:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jfrog.com\/wp-content\/uploads\/2019\/06\/tallying-up_social-1.png\" \/>\n<meta name=\"author\" content=\"giannit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Was GitHub und Artifactory alles bieten\" \/>\n<meta name=\"twitter:description\" content=\"Wie schl\u00e4gt sich der Package Manager von GitHub im Vergleich zu Artifactory? Ein kurzer \u00dcberblick zeigt, was das f\u00fcr Ihre Repositories und DevOps bedeutet &gt;&gt;\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/jfrog.com\/wp-content\/uploads\/2019\/06\/tallying-up_social.png\" \/>\n<meta name=\"twitter:creator\" content=\"@jfrog\" \/>\n<meta name=\"twitter:site\" content=\"@jfrog\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"giannit\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\"},\"author\":{\"name\":\"giannit\",\"@id\":\"https:\/\/jfrog.com\/de\/#\/schema\/person\/b554ace14b37da5eed75bbfc7dd1c1af\"},\"headline\":\"GitHub Packages vs. Artifactory\",\"datePublished\":\"2019-06-22T09:38:53+00:00\",\"dateModified\":\"2024-04-10T13:41:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\"},\"wordCount\":1230,\"publisher\":{\"@id\":\"https:\/\/jfrog.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\",\"url\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\",\"name\":\"Artifactory- im Vergleich zur GitHub Package Registry FAQs | JFrog Artifactory\",\"isPartOf\":{\"@id\":\"https:\/\/jfrog.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png\",\"datePublished\":\"2019-06-22T09:38:53+00:00\",\"dateModified\":\"2024-04-10T13:41:10+00:00\",\"description\":\"Wie schneidet der Package Manager von GitHub im Vergleich zu Artifactory ab? Ein kurzer \u00dcberblick der Leistungsf\u00e4higkeiten zeigt, was dies f\u00fcr Ihre Repositories und DevOps bedeutet.\",\"breadcrumb\":{\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage\",\"url\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png\",\"contentUrl\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png\",\"width\":203,\"height\":148,\"caption\":\"Artifactory vs GitHub\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/jfrog.com\/de\/homepage-2024\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GitHub Packages vs. Artifactory\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jfrog.com\/de\/#website\",\"url\":\"https:\/\/jfrog.com\/de\/\",\"name\":\"JFrog\",\"description\":\"Deliver Trusted Software Releases at Speed and Scale\",\"publisher\":{\"@id\":\"https:\/\/jfrog.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jfrog.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jfrog.com\/de\/#organization\",\"name\":\"JFrog\",\"url\":\"https:\/\/jfrog.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/jfrog.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2025\/05\/27095207\/Logo.svg\",\"contentUrl\":\"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2025\/05\/27095207\/Logo.svg\",\"width\":74,\"height\":73,\"caption\":\"JFrog\"},\"image\":{\"@id\":\"https:\/\/jfrog.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/artifrog\",\"https:\/\/x.com\/jfrog\",\"https:\/\/www.linkedin.com\/company\/455737\",\"https:\/\/www.youtube.com\/channel\/UCh2hNg76zo3d1qQqTWIQxDg\",\"https:\/\/www.wikidata.org\/wiki\/Q98608948\"],\"description\":\"We set out on our Liquid Software journey in 2008, with the mission to transform the way enterprises manage and release software updates. The world expects software to update continuously, securely, non-intrusively and without user intervention. This hyper-connected experience can only be enabled by automation with an end-to-end DevOps platform and a binary-centric focus. With this in mind, we\u2019ve developed the JFrog Platform, ushering in a new era of DevOps and DevSecOps standards that power continuous updates. More than a decade after our founding, with thousands of customers and millions of users globally, JFrog has become the \u201cDatabase of DevOps\u201d and the de-facto standard in release and update management.\",\"legalName\":\"Jfrog, Inc.\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1001\",\"maxValue\":\"5000\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jfrog.com\/de\/#\/schema\/person\/b554ace14b37da5eed75bbfc7dd1c1af\",\"name\":\"giannit\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/jfrog.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fca3c188acf34ea94b72429eb16d496a8d0b50af476289bb5f51c8283e5c5b1c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fca3c188acf34ea94b72429eb16d496a8d0b50af476289bb5f51c8283e5c5b1c?s=96&d=mm&r=g\",\"caption\":\"giannit\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Artifactory- im Vergleich zur GitHub Package Registry FAQs | JFrog Artifactory","description":"Wie schneidet der Package Manager von GitHub im Vergleich zu Artifactory ab? Ein kurzer \u00dcberblick der Leistungsf\u00e4higkeiten zeigt, was dies f\u00fcr Ihre Repositories und DevOps bedeutet.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts\/81787","og_locale":"de_DE","og_type":"article","og_title":"Was GitHub und Artifactory alles bieten","og_description":"Wie schl\u00e4gt sich der Package Manager von GitHub im Vergleich zu Artifactory? Ein kurzer \u00dcberblick zeigt, was das f\u00fcr Ihre Repositories und DevOps bedeutet >>","og_url":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/","og_site_name":"JFrog","article_publisher":"https:\/\/www.facebook.com\/artifrog","article_published_time":"2019-06-22T09:38:53+00:00","article_modified_time":"2024-04-10T13:41:10+00:00","og_image":[{"url":"https:\/\/jfrog.com\/wp-content\/uploads\/2019\/06\/tallying-up_social-1.png"}],"author":"giannit","twitter_card":"summary_large_image","twitter_title":"Was GitHub und Artifactory alles bieten","twitter_description":"Wie schl\u00e4gt sich der Package Manager von GitHub im Vergleich zu Artifactory? Ein kurzer \u00dcberblick zeigt, was das f\u00fcr Ihre Repositories und DevOps bedeutet >>","twitter_image":"https:\/\/jfrog.com\/wp-content\/uploads\/2019\/06\/tallying-up_social.png","twitter_creator":"@jfrog","twitter_site":"@jfrog","twitter_misc":{"Written by":"giannit","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#article","isPartOf":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/"},"author":{"name":"giannit","@id":"https:\/\/jfrog.com\/de\/#\/schema\/person\/b554ace14b37da5eed75bbfc7dd1c1af"},"headline":"GitHub Packages vs. Artifactory","datePublished":"2019-06-22T09:38:53+00:00","dateModified":"2024-04-10T13:41:10+00:00","mainEntityOfPage":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/"},"wordCount":1230,"publisher":{"@id":"https:\/\/jfrog.com\/de\/#organization"},"image":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png","articleSection":["Unkategorisiert"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/","url":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/","name":"Artifactory- im Vergleich zur GitHub Package Registry FAQs | JFrog Artifactory","isPartOf":{"@id":"https:\/\/jfrog.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage"},"image":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage"},"thumbnailUrl":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png","datePublished":"2019-06-22T09:38:53+00:00","dateModified":"2024-04-10T13:41:10+00:00","description":"Wie schneidet der Package Manager von GitHub im Vergleich zu Artifactory ab? Ein kurzer \u00dcberblick der Leistungsf\u00e4higkeiten zeigt, was dies f\u00fcr Ihre Repositories und DevOps bedeutet.","breadcrumb":{"@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#primaryimage","url":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png","contentUrl":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2019\/06\/20130759\/203x148-2.png","width":203,"height":148,"caption":"Artifactory vs GitHub"},{"@type":"BreadcrumbList","@id":"https:\/\/jfrog.com\/de\/blog\/artifactory-vs-github-packages-faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jfrog.com\/de\/homepage-2024\/"},{"@type":"ListItem","position":2,"name":"GitHub Packages vs. Artifactory"}]},{"@type":"WebSite","@id":"https:\/\/jfrog.com\/de\/#website","url":"https:\/\/jfrog.com\/de\/","name":"JFrog","description":"Deliver Trusted Software Releases at Speed and Scale","publisher":{"@id":"https:\/\/jfrog.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jfrog.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/jfrog.com\/de\/#organization","name":"JFrog","url":"https:\/\/jfrog.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/jfrog.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2025\/05\/27095207\/Logo.svg","contentUrl":"https:\/\/speedmedia2.jfrog.com\/08612fe1-9391-4cf3-ac1a-6dd49c36b276\/media.jfrog.com\/wp-content\/uploads\/2025\/05\/27095207\/Logo.svg","width":74,"height":73,"caption":"JFrog"},"image":{"@id":"https:\/\/jfrog.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/artifrog","https:\/\/x.com\/jfrog","https:\/\/www.linkedin.com\/company\/455737","https:\/\/www.youtube.com\/channel\/UCh2hNg76zo3d1qQqTWIQxDg","https:\/\/www.wikidata.org\/wiki\/Q98608948"],"description":"We set out on our Liquid Software journey in 2008, with the mission to transform the way enterprises manage and release software updates. The world expects software to update continuously, securely, non-intrusively and without user intervention. This hyper-connected experience can only be enabled by automation with an end-to-end DevOps platform and a binary-centric focus. With this in mind, we\u2019ve developed the JFrog Platform, ushering in a new era of DevOps and DevSecOps standards that power continuous updates. More than a decade after our founding, with thousands of customers and millions of users globally, JFrog has become the \u201cDatabase of DevOps\u201d and the de-facto standard in release and update management.","legalName":"Jfrog, Inc.","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1001","maxValue":"5000"}},{"@type":"Person","@id":"https:\/\/jfrog.com\/de\/#\/schema\/person\/b554ace14b37da5eed75bbfc7dd1c1af","name":"giannit","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/jfrog.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fca3c188acf34ea94b72429eb16d496a8d0b50af476289bb5f51c8283e5c5b1c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fca3c188acf34ea94b72429eb16d496a8d0b50af476289bb5f51c8283e5c5b1c?s=96&d=mm&r=g","caption":"giannit"}}]}},"_links":{"self":[{"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts\/81787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/users\/140"}],"replies":[{"embeddable":true,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/comments?post=81787"}],"version-history":[{"count":10,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts\/81787\/revisions"}],"predecessor-version":[{"id":128678,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/posts\/81787\/revisions\/128678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/media\/46502"}],"wp:attachment":[{"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/media?parent=81787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/categories?post=81787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jfrog.com\/de\/wp-json\/wp\/v2\/tags?post=81787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}